{"id":813,"date":"2007-04-27T20:46:28","date_gmt":"2007-04-27T20:46:28","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=813"},"modified":"2007-04-27T20:46:28","modified_gmt":"2007-04-27T20:46:28","slug":"strahlende-goetter-des-ostens-ciruelo-cabral","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2007\/04\/strahlende-goetter-des-ostens-ciruelo-cabral\/","title":{"rendered":"Strahlende G\u00f6tter des Ostens (Ciruelo Cabral)"},"content":{"rendered":"<p>Zur Zeit der Tangdynastie, vor mehr als tausend Jahren, war China ein Reich der Wunder, ein Land, wo die K\u00fcnste eine Vollkommenheit erreicht hatten, von der die V\u00f6lker des Westens nicht einmal tr\u00e4umen konnten. Die Hauptstadt Tschangan, gesch\u00fctzt durch hohe Mauern mit zahlreichen Toren, war von einem Netz breiter Prachtstra\u00dfen durchzogen, und unter den Ziegeld\u00e4chern der Palastwerkst\u00e4tten arbeiteten Handwerker, die groben Lehm in allerfeinstes durchscheinendes Porzellan zu verwandeln verstanden und stumpfes Erz in gl\u00e4nzende Skulpturen, so lebensecht, da\u00df sie zu atmen schienen. Aus dem Gespinst der Raupen schufen sie hauchd\u00fcnne Seidenstoffe, und mit Erde und B\u00e4umen gestalteten sie G\u00e4rten von juwelengleicher Vollkommenheit. In einem solchen Garten, geschm\u00fcckt mit stillen Seen, die angelegt waren, um Mond und Sterne zu spiegeln, mit Br\u00fcckenb\u00f6gen und luftigen Aussichtspavillons, lebten einst zwei Drachen. Dieser Garten, den der Eremit Lu Kuei Meng in seiner kunstvollen Handschrift beschrieb, geh\u00f6rte einem Edelmann, der nicht weit von Tschangan auf dem Land lebte. Er war ein Sammler von Sch\u00e4tzen der Natur. Schwerf\u00e4llige Pandas aus den Grenzgebieten Tibets verbargen sich scheu zwischen den Bambushalmen des Gartens, goldgefiederte Pfauen und Kicherdrosseln flatterten hinter seinen durchbrochenen Mauern, Yaks und mongolische Dromedare streiften durch seine Glyzinien, ein sibirischer Tiger trottete durch sein Teehaus, und in dem glasklaren, spiegelnden Teich hauste das Drachenpaar.  Die Drachen, die mit allen K\u00f6stlichkeiten gef\u00fcttert wurden, die ein Sterblicher zu bieten vermochte, waren zahme, durch die Gefangenschaft tr\u00e4ge gewordene Gesch\u00f6pfe. Tag f\u00fcr Tag lagen sie regungslos auf einer k\u00fcnstlichen Insel im See in der Sonne, ihre blauen und roten Schuppen schillerten;ihre faltigen Lider waren \u00fcber gelben Augen halb geschlossen. In kurzen Abst\u00e4nden glitten sie ins k\u00fchle Wasser und begaben sich ans Seeufer, wo gro\u00dfe Sch\u00fcsseln aus feinem Porzelan f\u00fcr sie standen, gef\u00fcllt mit Kormoran und Gans, gebratenen Schwalben und Haien, mit Ente und Schwein.  Drachen, so berichtete Lu Kuei Meng, waren stets gefr\u00e4\u00dfig:&#8220;Die gro\u00dfen Wale in allen Meeren reichen nicht aus, um den Appetit der Drachen zu stillen. &#8220; Durch unentwegte F\u00fctterung wurde das in Gefangenschaft gehaltene Paar sanftm\u00fctig und etwas von ihrer Drachennatur ging den beiden verloren:Inzwischen ganz und gar erdgebunden, hatten sie kaum noch \u00c4hnlichkeit mit den wilden Geistern von Wind und Wasser, die sie einst gewesen waren.  Eines Tages schwebte ein wilder Drache hoch \u00fcber den Ziegeld\u00e4chern der Palasth\u00e4user. Als Herr des Windes bewegte er sich kreisend und t\u00e4nzelnd nach Art des Drachenfluges mit m\u00e4chtigen Schwingen auf den Luftstr\u00f6mungen. Schlie\u00dflich ersp\u00e4hten seine weitblickenden Augen den Garten mit den silberbl\u00e4ttrigen Weiden und den wei\u00dfbl\u00fchenden Pflaumenb\u00e4umen, und auf dem glasklaren See sah er zwei Wesen seiner Art, wie sie sich in der Sonne w\u00e4rmten. Der Drache schwebte in gem\u00e4chlichen Kreisen herab, bis er sich schlie\u00dflich auf dem Dach des Teehauses niederlie\u00df, dessen First sich unter seinem Gewicht bog.  Er beobachtete die gefangenen Drachen, er betrachtete die mit Speisen \u00fcberh\u00e4uften Sch\u00fcsseln, und mit hallender Donnerstimme begann er in seiner Sprache zu den beiden zu sprechen. &#8222;Fliegt mit mir in die Freiheit, Br\u00fcder&#8220;, sagte er. &#8222;Wohnt in den Tiefen der Gew\u00e4sser und schwebt am Himmel. Rastet in Gefilden jenseits der Grenzen der L\u00fcfte. Wir sind kein Spielzeug f\u00fcr Sterbliche, sondern Geister, die auf den Winden reiten und die Wolken vor sich herblasen. &#8220; Doch die Drachen des Edelmannes waren verdorbene Kreaturen;es ist durchaus m\u00f6glich, da\u00df ihre erschlafften Schwingen die F\u00e4higkeit zu fliegen verloren hatten. Sie \u00f6ffneten die Augen, als das wilde Wesen sprach, doch ihre schweren Kiefer blieben auf dem warmen Felsgestein im See liegen. Die goldenen Augen schlossen sich langsam wieder. Die Drachen r\u00fchrten sich nicht.  Abermals sprach die donnernde Stimme:&#8220;Wer bei Menschen lebt, wird f\u00fcr Menschen sterben. &#8220; Und mit seinen ausladenden Schwingen die Luft umgreifend, erhob sich der wilde Drache und schwebte kreisend h\u00f6her und h\u00f6her in den tiefblauen Himmel hinein, bis er den Blicken entschwand.  Drachen besa\u00dfen die Gabe der Vorhersehung, und die Prophezeiung erf\u00fcllte sich. Lu Kuei Meng schildert in seinem Bericht nicht, wie es dazu kam, aber der Palast des Edelmannes wurde gest\u00fcrmt und gepl\u00fcndert, die Bewohner wurden hingerichtet, die Menagerie geschlachtet. Nur die kostbaren Drachen lie\u00df man am Leben. Sie wurden in Ketten nach Tschangan geschafft, in einem Triumphzug durch die breiten Prachtstra\u00dfen gef\u00fchrt und anschlie\u00dfend zum Palast des Kaisers gebracht, wo man die Wundertiere den gelangweilten H\u00f6flingen zur Unterhaltung vorf\u00fchrte. Danach wurden die Drachen geschlachtet und verzehrt. <\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Zur Zeit der Tangdynastie, vor mehr als tausend Jahren, war China ein Reich der Wunder, ein Land, wo die K\u00fcnste eine Vollkommenheit erreicht hatten, von der die V\u00f6lker des Westens nicht einmal tr\u00e4umen konnten. Die Hauptstadt Tschangan, gesch\u00fctzt durch hohe Mauern mit zahlreichen Toren, war von einem Netz breiter Prachtstra\u00dfen durchzogen, und unter den Ziegeld\u00e4chern [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-813","post","type-post","status-publish","format-standard","hentry","category-fantasy"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=813"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/813\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}