{"id":792,"date":"2010-05-21T10:24:29","date_gmt":"2010-05-21T10:24:29","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=792"},"modified":"2011-04-25T22:19:25","modified_gmt":"2011-04-25T21:19:25","slug":"ta-barron-merlins-drache-2","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2010\/05\/ta-barron-merlins-drache-2\/","title":{"rendered":"T.A. Barron &#8211; Merlins Drache"},"content":{"rendered":"<p><a href=\"http:\/\/www.drachenserver.de\/wordpress\/wp-content\/images\/shopping\/books\/t_a_barron_-_merlins_drache.jpg\" rel=\"lightbox[792]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin-right: 5px;\" title=\"Merlins Drache Cover\" src=\"http:\/\/www.drachenserver.de\/wordpress\/wp-content\/images\/shopping\/books\/t_a_barron_-_merlins_drache.jpg\" alt=\"\" width=\"100\" height=\"140\" \/><\/a>Als der Weltenbaum Avalon geboren wird, bricht zu dessen Wurzeln ein kleines Gesch\u00f6pf aus seinem Ei hervor und in die neue Welt. Basil ist ein kleiner Drache, der nicht gro\u00df ist, aber Gr\u00f6\u00dfe beweist und allein durch die besonderen Umst\u00e4nde seiner Geburt einst bedeutsam sein k\u00f6nnte. Bis aber auch ihm das bewusst wird, ist es ein langer Weg. Besonders f\u00fcr so einen kleinen Drachen, der sich auf die Suche nach dem gro\u00dfen Zauberer Merlin macht, um ihn vor einer gro\u00dfen Gefahr zu warnen.<\/p>\n<p>Der erste Band der Trilogie um Merlin und seinen Drachen Basil beginnt langsam, fantastisch und mit viel sch\u00f6pferischer Kraft. Angesiedelt irgendwo zwischen Barrons Merlin Pentalogie und der Avalon Trilogie erlebt der Drache Basil ein Abenteuer, welches f\u00fcr ihn zu gro\u00df zu sein scheint. Barron beschreibt seine Welt und die Eindr\u00fccke auf seinen Protagonisten teils seitenlang in tollen Worten und mit viel Gef\u00fchl. So entsteht das Bild in einer sich entwickelnden, sch\u00f6nen aber auch gef\u00e4hrlichen Welt zu schweben, aber nie ganz Teil davon zu werden. Seinem Protagonisten schreibt er immer schlimmer werdende Zweifel an der eigenen Bedeutsamkeit auf den Leib. Da kann kommen was will, jegliche Gefahr gemeistert, jeder Gegner \u00fcberwunden werden, Basil f\u00fchlt sich klein und will gr\u00f6\u00dfer sein. Es vergehen keine 10 Seiten in denen dies nicht dem Leser noch einmal unter die Nase gerieben werden muss. Kaum hat er eine \u00fcberm\u00e4chtige Gefahr gemeistert, muss er selbst auch schon wieder gerettet werden. Das ganze Buch l\u00e4uft letztendlich auf die Begegnung mit dem Zauberer Merlin und die Erf\u00fcllung einer Vision hinaus. Schade, dass dies bereits durch den Klappentext komplett vorweg genommen wurde.<\/p>\n<p>Trotz der vorhersehbaren Geschichte und dem offensichtlichen Ende gl\u00e4nzt das Buch auf Grund seiner Sprachgewandtheit und l\u00e4sst sich zur Anregung der eigenen Fantasie toll lesen.<\/p>\n<p><a href=\"http:\/\/www.amazon.de\/Merlins-Drache-Roman-Thomas-Barron\/dp\/3423713828\/dragonslayer_21\/\" target=\"_blank\">Merlins Drache<\/a> bei Amazon<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Als der Weltenbaum Avalon geboren wird, bricht zu dessen Wurzeln ein kleines Gesch\u00f6pf aus seinem Ei hervor und in die neue Welt. Basil ist ein kleiner Drache, der nicht gro\u00df ist, aber Gr\u00f6\u00dfe beweist und allein durch die besonderen Umst\u00e4nde seiner Geburt einst bedeutsam sein k\u00f6nnte. Bis aber auch ihm das bewusst wird, ist es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[552,551],"class_list":["post-792","post","type-post","status-publish","format-standard","hentry","category-rezensionen","tag-basilgarrad","tag-t-a-barron"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=792"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/792\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}