{"id":755,"date":"2006-12-14T21:27:12","date_gmt":"2006-12-14T20:27:12","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=755"},"modified":"2011-09-21T00:22:08","modified_gmt":"2011-09-20T23:22:08","slug":"eragon-der-film","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2006\/12\/eragon-der-film\/","title":{"rendered":"Eragon &#8211; Der Film"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left;\" title=\"\" src=\"http:\/\/www.drachenserver.de\/wordpress\/wp-content\/images\/news\/2006\/eragonposter.jpg\" alt=\"\" width=\"150\" height=\"212\" border=\"0\" hspace=\"6\" \/>In der Welt Alaga\u00ebsia bewahrten einst Drachenreiter mit ihren gefl\u00fcgelten Echsen das Land. Bis sich Galbatorix, einer von ihnen, die Macht unter den Nagel riss und alle anderen Drachen ausrottete.<\/p>\n<p>Der Elfe Arya, einer Verb\u00fcndeten der Rebellen, die sich gegen Galbatorix auflehnen, gelingt es, ein Drachenei des b\u00f6sen K\u00f6nigs zu stehlen. Das Schicksal l\u00e4sst dieses Drachenei dem Bauernjungen Eragon zukommen, dessen Leben sich durch dieses Ereignis fundamental \u00e4ndern soll. Aus dem Ei schl\u00fcpft eine Drachin, die sich dem Jungen bald als Saphira vorstellt und ihm offenbart: Er ist der neue Drachenreiter!<\/p>\n<p>Brom, der alte Geschichtenerz\u00e4hler aus Eragons Dorf, scheint mehr \u00fcber die Drachen und deren Reiter zu wissen. Mit ihm zusammen machen sich Eragon und Saphira auf, sich den Rebellen anzuschlie\u00dfen. Doch sie werden verfolgt von Durza, einem Schatten, dem schrecklichsten und m\u00e4chtigsten Diener Galbatorix&#8216; &#8230;<\/p>\n<p>Mannomann, da ist der Kerl noch so jung und hat es schon geschafft, es auf die gro\u00dfe Leinwand zu bringen. Nein, die Rede ist weder von Titelcharakter Eragon noch von dessen Schauspieler Edward Speleers, sondern von Christopher Paolini, dem Autor der enorm erfolgreichen Vorlage von &#8222;Eragon &#8211; Das Verm\u00e4chtnis der Drachenreiter&#8220;. Analog zu den Respektsbekundungen, die der junge Mann bekam, weil er seinen Roman angeblich mit 15 Jahren schrieb &#8211; was ich nebenbei nicht mehr h\u00f6ren kann, schlie\u00dflich war er bereits 19, als das Buch dann auch irgendwann mal endlich erschien &#8211; k\u00f6nnte man nun schwer davon beeindruckt sein, dass seine Geschichte, nun, da er 23 ist, als Multmillionen-Dollar-Produktion mit aufwendigen Spezialeffekten und teurer Ausstattung weltweit auf den Leinw\u00e4nden kultureller Popkulturtempel l\u00e4uft, die mit ihrem enormen Werbebudget mich selbst beim Spielen des Autorennspiels &#8222;TrackMania Nations&#8220; nicht mit Bandenwerbung verschont. Paolini kann jedenfalls stolz auf sich sein &#8211; aber realisiert er auch, dass sein Buch, welches ich zugegebenerma\u00dfen immer noch ganz nett finde, seine Umsetzung als perfekt geplantes, kaltes Marketingprodukt findet? Die Eckdaten des Konzepts dieser Produktion sind jedenfalls klar ersichtlich: Risikominimierung durch die bereits etablierte Marke des Buchs, Fantasy als aktuell gewinntr\u00e4chtiges Trendgenre, junge Haupt- und etablierte Nebendarsteller, Kernzielgruppe 12 &#8211; 15j\u00e4hrige Teenager. Wenn man in der Nachmittagsvorstellung am Premierentag den Kopf mal nach rechts und links drehte, wurde sofort klar: Dieses Konzept ist exakt aufgegangen.<\/p>\n<p>Und wo es viel Konzept und viel Marketing gibt, bleibt leider meist nur wenig Film \u00fcbrig. &#8222;Eragon&#8220; ist also, wahrscheinlich ganz nach Konzept, ein unterhaltsamer Fantasy-Film f\u00fcr Jugendliche geworden, die f\u00fcr &#8222;Die Chroniken von Narnia&#8220; zu alt und f\u00fcr &#8222;Der Herr der Ringe&#8220; zu jung sind. Eine Seele hat der Film dabei freilich nicht. &#8222;Eragon&#8220; ist zu 100 Prozent Story und zu 0 Prozent Charaktere, was vielleicht gar nicht so schlimm ist, wenn diese wie das 35. Element des Periodensystems oder wie der iranische Pr\u00e4sident hei\u00dfen. Die Geschichte des Buchs wird jedenfalls auf Fast-Forward-Modus durchflitzt, Zeit zum Durchatmen bleibt da eigentlich kaum &#8211; Zeit f\u00fcr Langeweile gl\u00fccklicherweise auch nicht. Dennoch wirkt die Story so erz\u00e4hlt wie ein gro\u00dfer Flickenteppich, der hier mal eben einen neuen Charakter und dort mal eben eine finale Schlacht aus dem Hut zaubert, die \u00fcbrigens sowieso eher wie eine bessere Kneipenschl\u00e4gerei aussieht.<\/p>\n<p>Aber immerhin hat &#8222;Eragon&#8220; einen Drachen (der im Konzept wahrscheinlich unter dem Punkt &#8222;Unique Selling Point&#8220; gef\u00fchrt wird). Klar gibt Saphira tricktechnisch ordentlich was her. Sie sieht nicht zu klischeehaft aus, hat ein starres, reptilienhaftes Minenspiel, was sich deutlich von dem menschelnden Draco aus &#8222;DragonHeart&#8220; absetzt und macht deswegen stets einen befremdlich-gleichg\u00fcltigen Eindruck, was man als gelungen betrachten sollte &#8211; schlie\u00dflich h\u00e4tten diese widerlich s\u00fc\u00dfen Kindereien mit der jungen Saphira am Anfang des Films auch noch ewig weitergehen k\u00f6nnen. Aber wenn sie abhebt, bebt das Kino &#8211; und das ist cool. Und wenn sie sich im Finale mit einem monstr\u00f6sen Dings aus Schall und Rauch duelliert, ist das recht aufregend. Man merkt, mit Tricks kann Regisseur und Effektspezialist Stephen Fangmeier sehr gut umgehen, mit Schneidearbeit und Charakteren eher weniger. Nat\u00fcrlich sind die meisten Figuren \u00fcbelste Stereotypen, aus dem Popkulturfundus von Tolkien und Lucas entlehnt, aber der Film kommt zwischen all der Story gerade mal so dazu, sie \u00fcberhaupt als solche zu definieren. Die Leistungen der Schauspieler sind dabei nat\u00fcrlich nicht weiter nennenswert, lediglich Jeremy Irons als Mentor Brom schafft es, zumindest so zu tun, als h\u00e4tten die Worte, die er spricht, irgendeine Bedeutung. Newcomer Edward Speleers trifft den Hauptcharakter als einen arroganten Jugendlichen mit \u00fcbersteigertem Geltungsbed\u00fcrfnis nebenbei bemerkt ebenfalls ganz gut. Womit wir wieder bei Christopher Paolini w\u00e4ren, von dem man nach Schauen dieses Films sagen muss, dass sein gr\u00f6\u00dfter Verdienst es wahrscheinlich bleiben wird, die W\u00f6rter &#8222;ambidexter&#8220; und &#8222;Quadrizeps&#8220; in die Fantasy-Literatur eingef\u00fchrt zu haben.<\/p>\n<p><ins>Fazit:<\/ins> Man kommt aus dem Kino und wurde unterhalten, aber mit dem verst\u00e4rkten Bewusstsein, dass &#8222;Eragon&#8220; reine Massenkonfektionsware ist. Im Abspann l\u00e4uft ein Song von Avril Lavigne. Wer die ernsthaft gut findet, wird an &#8222;Eragon&#8220; sicherlich sehr viel Freude finden. \u00a9 Doc, <a href=\"http:\/\/www.die-subkultur.net\/Film.php?seite=eragonfilm\">Quelle<\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>In der Welt Alaga\u00ebsia bewahrten einst Drachenreiter mit ihren gefl\u00fcgelten Echsen das Land. Bis sich Galbatorix, einer von ihnen, die Macht unter den Nagel riss und alle anderen Drachen ausrottete. Der Elfe Arya, einer Verb\u00fcndeten der Rebellen, die sich gegen Galbatorix auflehnen, gelingt es, ein Drachenei des b\u00f6sen K\u00f6nigs zu stehlen. Das Schicksal l\u00e4sst dieses [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[421,324,93],"class_list":["post-755","post","type-post","status-publish","format-standard","hentry","category-rezensionen","tag-christopher-paolini","tag-drachenfilm","tag-eragon"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=755"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/755\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}