{"id":719,"date":"2005-01-09T23:33:28","date_gmt":"2005-01-09T23:33:28","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=719"},"modified":"2005-01-09T23:33:28","modified_gmt":"2005-01-09T23:33:28","slug":"chris-bunch-herrscher-der-luefte","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2005\/01\/chris-bunch-herrscher-der-luefte\/","title":{"rendered":"Chris Bunch-Herrscher der L\u00fcfte"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.drachenserver.de\/wordpress\/wp-content\/images\/Drachen\/Books\/chris_bunch_herrscher_der_luefte.jpg\" hspace=\"6\" alt=\"\" title=\"\" border=\"0\" style=\"float: left;\" \/>Schon als kleiner Junge war Hal Kailas ein Drachenliebhaber. Zwangsweise verlie&szlig; er fr&uuml;h das Elternhaus, um sich als Weltenbummler durch das Leben zu schlagen und seinen Traum zu verfolgen, ein Drachenreiter zu werden. Als sich die Chance bietet als Gehilfe bei einem Kunstflug &#8211; Drachenreiter zu arbeiten, nimmt er dankend an. Doch das Gl&uuml;ck des Jungen w&auml;hrt nicht lang. Nach dem Tod seines Meisters heuert er bei der Armee an, die sich auf einen gro&szlig;en Krieg vorbereitet und den Jungen als Kundschafter seine ersten Sporen verdienen l&auml;sst, bevor er sich selbst bei den Drachenreitern anmeldet. Hier aber fangen f&uuml;r den Jungen Mann die eigentlichen Grauen des Krieges erst an.<br \/>Der Lebensweg des Jungen Kriegshelden Hal Kailas ist gezeichnet von Schmerz, Tod und Verlusten. Da er schon fr&uuml;h in die Armee berufen wurde, hatte er nie eine richtige Kindheit und nur wenige Freunde. Gepr&auml;gt durch das viele Grauen in seinen fr&uuml;hen Jahren verwundert es nicht, dass er seine Erf&uuml;llung selbst nur im Krieg und an der Front findet und beweist sich dabei schnell als geschickter K&auml;mpfer und Drachenflieger, als echter Kriegsheld. Damit endet aber auch schon die Story des Buches, denn der Rest der Seiten ist gef&uuml;llt mit der ersch&ouml;pfenden Beschreibung von Kriegstaktiken mit denen die b&ouml;sen ,barbarischen Gegner vernichtet werden k&ouml;nnen, um den Krieg zu gewinnen. Hal Kailas steht dabei an der Spitze der frisch ausgehobenen Drachenfliegerstaffel, die sich zwar zun&auml;chst nur als Kundschafter verdingen, jedoch zunehmend entscheidender f&uuml;r den Krieg werden.<br \/>W&auml;hrend der Lekt&uuml;re des Buches war ich hin und her gerissen. Einerseits spielen die Drachen und die Art wie sie beschrieben werden eine nette Abwechslung zu anderen B&uuml;chern dar, da sie zwar komplett als Reittiere angesehen werden, aber keine allm&auml;chtigen Biester mit &uuml;bernat&uuml;rlichen F&auml;higkeiten sind. Auch ihre Reiter sind keine &uuml;bermenschlichen Wesen. Aber andererseits war ich durch die deutliche N&auml;he zum zweiten Weltkrieg irritiert. St&auml;ndig hatte ich das Gef&uuml;hl in einer Story zu h&auml;ngen, deren Rahmenhandlung vollst&auml;ndig austauschbar ist. Genauso gut h&auml;tte man den Fantasyrahmen durch Deutschland im 20 Jahrhundert ersetzen k&ouml;nnen und die Drachen durch die ersten Kampfflugzeuge. Derart dicht an den Weltkriegen angelehnt, beweist das Buch zwar erstaunlich detailreich wie grausam der Krieg und wie ignorant die Verantwortlichen sein k&ouml;nnen, aber auch wie blutr&uuml;nstig ein Protagonist sein kann und dennoch als Held gefeiert wird.<br \/>Der Fantasyroman von Chris Bunch ist eine Art Kriegsdokumentation im Gewand einer Fantasywelt, die alle Schrecken und auch die Ver&auml;nderungen und den Schmerz der Teilnehmer wiederspiegelt. Das Buch ist eine Lekt&uuml;re die ich nur Sammlern empfehlen m&ouml;chte.<br \/><a target=\"_blank\" href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/3442241979\/ref=ase_dragonslayer-21\/\">Herrscher der L&uuml;fte<\/a> kann bei Amazon bestellt werden<\/p>\n<p><!--more--><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Schon als kleiner Junge war Hal Kailas ein Drachenliebhaber. Zwangsweise verlie&szlig; er fr&uuml;h das Elternhaus, um sich als Weltenbummler durch das Leben zu schlagen und seinen Traum zu verfolgen, ein Drachenreiter zu werden. Als sich die Chance bietet als Gehilfe bei einem Kunstflug &#8211; Drachenreiter zu arbeiten, nimmt er dankend an. Doch das Gl&uuml;ck des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-719","post","type-post","status-publish","format-standard","hentry","category-rezensionen"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=719"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/719\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}