{"id":707,"date":"2004-04-09T13:19:00","date_gmt":"2004-04-09T13:19:00","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=707"},"modified":"2004-04-09T13:19:00","modified_gmt":"2004-04-09T13:19:00","slug":"dragonkin-buch-1","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2004\/04\/dragonkin-buch-1\/","title":{"rendered":"Dragonkin Buch 1"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/0743458540\/dragonslayer-21\"><img decoding=\"async\" alt=\"robin wayne bailey dragonkin buch 1\" src=\"http:\/\/www.drachenserver.de\/wordpress\/wp-content\/images\/news\/robin_wayne_bailey_dragonkin.jpg\" align=\"left\" border=\"0\" \/><\/a>Dragonkin Buch 1 \u2013 Robin Wayne Bailey<br \/><\/strong>Als die Magie der Welt entschwindet, vergeht die Zeit der Drachen. Ein neues Zeitalter r\u00fcckt unaufhaltsam heran, ein Zeitalter, welches von den Menschen dominiert wird. Wyvernwood, ein tiefer und mysteri\u00f6ser Wald in den L\u00e4ndern von Engmar, ist die letzte Zuflucht f\u00fcr alle, die nicht in diese neue Welt passen-Minotauren, Einh\u00f6rner, Satyre und Drachen-der letzte Ort, um in Frieden zu Leben. Doch selbst hier, fernab aller anderen V\u00f6lker, ist es nicht mehr sicher, wenn sich Fabelwesen mit den Menschen verb\u00fcnden\u2026<\/p>\n<p>Eines Tages \u00fcberschlagen sich die Ereignisse in Wyvernwood. Menschen, die sonst niemals nach Wyvernwood kommen w\u00fcrden, erscheinen in den dunklen W\u00e4ldern der Fabeltiere und Kidnappen einen jungen Minotauren. Voller Sorge machen sich der Drache Ronaldo, das letzte Einhorn Marian und der Kolibri Bumble auf den Weg ihn zu befreien und \u00fcberschreiten dabei die Grenzen Wyvernwoods in die L\u00e4nder der Menschen, wo Ihre Existenz Schrecken und Wunder zugleich bedeutet. Doch auch von innen droht Gefahr. Als der machtgierige Greif Gaunt seinen eigenen Vater hinterlistig ermordet, um selbst K\u00f6nig zu werden, verschiebt sich das Machtgef\u00fcge in Wyverwood gewaltig. Doch eindeutig zu weit gehen die Greifen, als sie sich gegen die unangefochtene Macht der Drachen wenden und ein schreckliches Attentat vollf\u00fchren.<\/p>\n<p>Robin Wayne Bailey\u2019s Geschichte \u201eDragonkin\u201c geh\u00f6rt in die \u00e4u\u00dferst seltene Sparte der Romane, die Drachen in der Hauptrolle haben. Vor ihm hat sich das bisher nur Graham Edwards in \u201eDer Basilisk\u201c getraut. Doch wo Edwards damals scheiterte eine wirklich einmalige Stimmung rund um eine fantastische Story zu schaffen, da brilliert Bailey. Die Wunder Wyvernwoods, der St\u00e4dte der Menschen, oder einfach nur ein Sonnenaufgang werden genau so beschrieben, wie sie sind: herrlich, schrecklich oder furchteinfl\u00f6ssend. Dabei bleibt sie jedoch vor allem eines: Phantastisch. Die Geschichte selbst ist dabei der Auftakt einer Trilogie, und endet mit einem Happy End, aber auch mit der Gewissheit, dass nichts von Dauer ist und die eigentliche Pr\u00fcfung erst bevor steht. Ich finde es sch\u00f6n endlich einmal wieder eine Geschichte zu lesen, die vom \u201eKleine Gruppe rettet die gesamte Welt\u201c-Schema abweicht und nicht mit weltvernichtenden Problemen beginnt. Dass sich daraus aber dennoch eine unglaublich wundervolle Geschichte entspinnen kann, beweist Bailey eindrucksvoll. Alle Charaktere sind liebevoll ausgearbeitet, mal lustig, mal tragisch oder gef\u00e4hrlich und dabei nie langweilig. Schon allein die Idee einen Kolibri als komisches Element in eine Gruppe zu integrieren ist sehr gut gelungen und wenn dieser Running-\u00e4h Flying Gag dann auch noch selbst eine charakterliche Ver\u00e4nderung vollf\u00fchrt, wie alle anderen Charaktere \u00fcbrigens auch, dann kann man mit Recht sagen, dass sich Bailey \u00fcber das was er sagen und ausdr\u00fccken wollte lange Gedanken gemacht hat. Abschlie\u00dfend zum ersten Buch kann ich nur noch sagen, dass ich mich darauf freue zu sehen, wie die Geschichte sich weiter entwickelt und ob Bailey es schafft im kritischen zweiten Teil einer Trilogie seinen furiosen ersten Teil noch zu toppen.<\/p>\n<p>Das Buch kann man bei Amazon kaufen: <a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/0743458540\/dragonslayer-21\">Dragon Kin bei Amazon<\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Dragonkin Buch 1 \u2013 Robin Wayne BaileyAls die Magie der Welt entschwindet, vergeht die Zeit der Drachen. Ein neues Zeitalter r\u00fcckt unaufhaltsam heran, ein Zeitalter, welches von den Menschen dominiert wird. Wyvernwood, ein tiefer und mysteri\u00f6ser Wald in den L\u00e4ndern von Engmar, ist die letzte Zuflucht f\u00fcr alle, die nicht in diese neue Welt passen-Minotauren, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-707","post","type-post","status-publish","format-standard","hentry","category-rezensionen"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=707"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/707\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}