{"id":30,"date":"2002-10-21T11:14:00","date_gmt":"2002-10-21T11:14:00","guid":{"rendered":"http:\/\/www.drachenserver.de\/wordpress\/?p=30"},"modified":"2011-04-07T09:40:50","modified_gmt":"2011-04-07T08:40:50","slug":"spiel-2002","status":"publish","type":"post","link":"https:\/\/www.drachenserver.de\/wordpress\/2002\/10\/spiel-2002\/","title":{"rendered":"Spiel 2002"},"content":{"rendered":"<p>Ich bin wieder hier!<br \/>Den ganzen Samstag \u00fcber durfte ich auf der gro\u00dfen Spiele und Comic Messe Spiel 2002 in Essen herumtoben und alles was ich hierzu sagen kann ist: PERFEKT. Es war der perfekte Tag f\u00fcr einen Drachenfreak. Mal ganz davon abgesehen, dass ich die neuesten Brettspiele testen durfte und jede menge Drachenskulpturen und anderer Illustrer Gestalten photographieren durfte, hatte ich endlich einmal die Chance Ciruelo Cabral, der Drachengott selbst kennenzulernen. Doch dabei nicht genug! Auch Larry Elmore und Dorian Cleavenger traf ich zu einem kleinen Schw\u00e4tzchen. Und wenn das einen Tag noch nicht perfekt macht, dann vielleicht die Tatsache, dass ich viele neue K\u00fcnstler kennenlernte und viele neue Quellen f\u00fcr Drachenbilder somit anbohren konnte!<br \/>Wer mehr Interesse hat zu erfahren was die Messe so alles zu bieten hatte, der kann sich ja meinen kleinen Bericht dazu durchlesen:<br \/><a href=\"http:\/\/www.dragonslayer.de\/?page=essenspiel02\">Zum Bericht<\/a><br \/>Es lohnt sich wirklich die Messe zu besuchen und wer n\u00e4chstes jahr Mitte Oktober noch nichts vor hat, der solle sich unbedingt im Forum melden und mit uns allen Gemeinsam dorthin fahren!<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Ich bin wieder hier!Den ganzen Samstag \u00fcber durfte ich auf der gro\u00dfen Spiele und Comic Messe Spiel 2002 in Essen herumtoben und alles was ich hierzu sagen kann ist: PERFEKT. Es war der perfekte Tag f\u00fcr einen Drachenfreak. Mal ganz davon abgesehen, dass ich die neuesten Brettspiele testen durfte und jede menge Drachenskulpturen und anderer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30","post","type-post","status-publish","format-standard","hentry","category-drachennews"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":0,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/posts\/30\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/media?parent=30"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/categories?post=30"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drachenserver.de\/wordpress\/wp-json\/wp\/v2\/tags?post=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}